{"id":330,"date":"2024-07-23T17:40:36","date_gmt":"2024-07-23T20:40:36","guid":{"rendered":"https:\/\/www.cartoriosdobrasil.org\/agenda\/aprenda-a-consultar-a-matricula-do-seu-imovel-gratuitamente-sem-precisar-pagar-pela-certidao\/"},"modified":"2024-07-23T17:40:36","modified_gmt":"2024-07-23T20:40:36","slug":"aprenda-a-consultar-a-matricula-do-seu-imovel-gratuitamente-sem-precisar-pagar-pela-certidao","status":"publish","type":"post","link":"https:\/\/www.cartoriosdobrasil.org\/agenda\/aprenda-a-consultar-a-matricula-do-seu-imovel-gratuitamente-sem-precisar-pagar-pela-certidao\/","title":{"rendered":"Aprenda a consultar a matr\u00edcula do seu im\u00f3vel gratuitamente sem precisar pagar pela certid\u00e3o"},"content":{"rendered":"<p>Os propriet\u00e1rios que realizaram transa\u00e7\u00f5es imobili\u00e1rias no \u00faltimo ano, como venda, doa\u00e7\u00e3o, compra, heran\u00e7a ou financiamento, devem incluir essas opera\u00e7\u00f5es em sua declara\u00e7\u00e3o de Imposto de Renda 2022. O prazo final para entrega do documento \u00e9 dia 31 deste m\u00eas.<\/p>\n<p>Al\u00e9m dos dados pessoais, \u00e9 necess\u00e1rio informar no campo &#8220;Descri\u00e7\u00e3o&#8221; detalhes como Inscri\u00e7\u00e3o Municipal (IPTU), endere\u00e7o, \u00e1rea e matr\u00edcula. No caso de falta da matr\u00edcula, \u00e9 importante localizar em qual cart\u00f3rio o im\u00f3vel foi registrado.<\/p>\n<p>Dentro do programa da Receita, na se\u00e7\u00e3o &#8220;Bens e Direitos&#8221;, devem ser inseridos os dados presentes na matr\u00edcula do im\u00f3vel, como tipo de propriedade, \u00e1rea constru\u00edda, data da compra, tipo de financiamento, status do financiamento e valor das parcelas restantes.<\/p>\n<p>Para acessar a matr\u00edcula do im\u00f3vel, o contribuinte pode utilizar a plataforma eletr\u00f4nica Servi\u00e7o de Atendimento Eletr\u00f4nico Compartilhado do Registro de Im\u00f3veis \u2013 SAEC, dispon\u00edvel em todo o Brasil.<\/p>\n<p>A plataforma permite a busca de bens e outros servi\u00e7os relacionados ao registro imobili\u00e1rio no pa\u00eds. O projeto \u00e9 gerenciado pelo Operador Nacional do Sistema de Registro Eletr\u00f4nico de Im\u00f3veis (ONR), com regula\u00e7\u00e3o e inspe\u00e7\u00e3o das opera\u00e7\u00f5es realizadas pelo Conselho Nacional de Justi\u00e7a (CNJ).<\/p>\n<p>Atrav\u00e9s do portal do SAEC, o contribuinte pode solicitar a &#8220;visualiza\u00e7\u00e3o de matr\u00edcula&#8221; para verificar os dados do im\u00f3vel, com a op\u00e7\u00e3o de salv\u00e1-los ou imprimir.<\/p>\n<p>Aqueles que precisam identificar o cart\u00f3rio onde o im\u00f3vel est\u00e1 registrado podem usar a ferramenta de &#8220;pesquisa de bens&#8221;, que requer o CPF ou CNPJ para localizar a propriedade. Os valores dos servi\u00e7os est\u00e3o em conformidade com a legisla\u00e7\u00e3o estadual e podem ser consultados no momento da solicita\u00e7\u00e3o.<\/p>\n<p>Entre na comunidade  e receba informa\u00e7\u00f5es gratuitas em seu Whatsapp!<\/p>\n<p>Por favor, certifique-se de que o texto reescrito atenda aos crit\u00e9rios de originalidade, qualidade e otimiza\u00e7\u00e3o para SEO conforme solicitado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os propriet\u00e1rios que realizaram transa\u00e7\u00f5es imobili\u00e1rias no \u00faltimo ano, como venda, doa\u00e7\u00e3o, compra, heran\u00e7a ou financiamento, devem incluir essas opera\u00e7\u00f5es em sua declara\u00e7\u00e3o de Imposto de Renda 2022. O prazo final para entrega do documento \u00e9 dia 31 deste m\u00eas. Al\u00e9m dos dados pessoais, \u00e9 necess\u00e1rio informar no campo &#8220;Descri\u00e7\u00e3o&#8221; detalhes como Inscri\u00e7\u00e3o Municipal (IPTU), endere\u00e7o, \u00e1rea e matr\u00edcula. No caso de falta da matr\u00edcula, \u00e9 importante localizar em qual cart\u00f3rio o im\u00f3vel foi registrado. Dentro do programa da Receita, na se\u00e7\u00e3o &#8220;Bens e Direitos&#8221;, devem ser inseridos os dados presentes na matr\u00edcula do im\u00f3vel, como tipo de propriedade, \u00e1rea <\/p>\n","protected":false},"author":1,"featured_media":332,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"yst_prominent_words":[],"class_list":["post-330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sobre-cartorios","has_thumb"],"_links":{"self":[{"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":0,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/media\/332"}],"wp:attachment":[{"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/tags?post=330"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.cartoriosdobrasil.org\/agenda\/wp-json\/wp\/v2\/yst_prominent_words?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}